{"id":1084,"count":1,"description":"","link":"https:\/\/hellaspindakaas.com\/el\/tag\/help-children-in-greece\/","name":"help children in greece","slug":"help-children-in-greece","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>help children in greece Archives - Hellas Pindakaas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hellaspindakaas.com\/el\/tag\/help-children-in-greece\/\" \/>\n<meta property=\"og:locale\" content=\"el_GR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"help children in greece Archives - Hellas Pindakaas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hellaspindakaas.com\/el\/tag\/help-children-in-greece\/\" \/>\n<meta property=\"og:site_name\" content=\"Hellas Pindakaas\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2015\/11\/front-color-edited.jpg?fit=1270%2C898&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1270\" \/>\n\t<meta property=\"og:image:height\" content=\"898\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@hellaspindakaas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/tag\\\/help-children-in-greece\\\/\",\"url\":\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/tag\\\/help-children-in-greece\\\/\",\"name\":\"help children in greece Archives - Hellas Pindakaas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/tag\\\/help-children-in-greece\\\/#breadcrumb\"},\"inLanguage\":\"el\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/tag\\\/help-children-in-greece\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hellaspindakaas.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"help children in greece\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/#website\",\"url\":\"https:\\\/\\\/hellaspindakaas.com\\\/\",\"name\":\"Hellas Pindakaas\",\"description\":\"online - \u03a4\u03bf \u03bd\u03bf\u03c3\u03c4\u03b9\u03bc\u03bf \u03c1\u03b1\u03b4\u03b9\u03bf\u03c6\u03c9\u03bd\u03bf \u03ba\u03b1\u03b9 \u03c3\u03c4\u03bf \u03b4\u03b9\u03b1\u03b4\u03b9\u03ba\u03c4\u03c5\u03bf\",\"publisher\":{\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hellaspindakaas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"el\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/#organization\",\"name\":\"Hellas Pindakaas\",\"url\":\"https:\\\/\\\/hellaspindakaas.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/hellaspindakaas.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO-hellas-pindakaas.jpg?fit=1734%2C1872&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/hellaspindakaas.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO-hellas-pindakaas.jpg?fit=1734%2C1872&ssl=1\",\"width\":1734,\"height\":1872,\"caption\":\"Hellas Pindakaas\"},\"image\":{\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HellasPindakaas\\\/\",\"https:\\\/\\\/x.com\\\/hellaspindakaas\",\"https:\\\/\\\/www.instagram.com\\\/hellaspindakaas\\\/?hl=en\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/nikos-koulousios-5023527\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/nikkokoul\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"help children in greece Archives - Hellas Pindakaas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hellaspindakaas.com\/el\/tag\/help-children-in-greece\/","og_locale":"el_GR","og_type":"article","og_title":"help children in greece Archives - Hellas Pindakaas","og_url":"https:\/\/hellaspindakaas.com\/el\/tag\/help-children-in-greece\/","og_site_name":"Hellas Pindakaas","og_image":[{"width":1270,"height":898,"url":"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2015\/11\/front-color-edited.jpg?fit=1270%2C898&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@hellaspindakaas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hellaspindakaas.com\/el\/tag\/help-children-in-greece\/","url":"https:\/\/hellaspindakaas.com\/el\/tag\/help-children-in-greece\/","name":"help children in greece Archives - Hellas Pindakaas","isPartOf":{"@id":"https:\/\/hellaspindakaas.com\/#website"},"breadcrumb":{"@id":"https:\/\/hellaspindakaas.com\/el\/tag\/help-children-in-greece\/#breadcrumb"},"inLanguage":"el"},{"@type":"BreadcrumbList","@id":"https:\/\/hellaspindakaas.com\/el\/tag\/help-children-in-greece\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hellaspindakaas.com\/"},{"@type":"ListItem","position":2,"name":"help children in greece"}]},{"@type":"WebSite","@id":"https:\/\/hellaspindakaas.com\/#website","url":"https:\/\/hellaspindakaas.com\/","name":"Hellas Pindakaas","description":"online - \u03a4\u03bf \u03bd\u03bf\u03c3\u03c4\u03b9\u03bc\u03bf \u03c1\u03b1\u03b4\u03b9\u03bf\u03c6\u03c9\u03bd\u03bf \u03ba\u03b1\u03b9 \u03c3\u03c4\u03bf \u03b4\u03b9\u03b1\u03b4\u03b9\u03ba\u03c4\u03c5\u03bf","publisher":{"@id":"https:\/\/hellaspindakaas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hellaspindakaas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"el"},{"@type":"Organization","@id":"https:\/\/hellaspindakaas.com\/#organization","name":"Hellas Pindakaas","url":"https:\/\/hellaspindakaas.com\/","logo":{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/hellaspindakaas.com\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2018\/03\/LOGO-hellas-pindakaas.jpg?fit=1734%2C1872&ssl=1","contentUrl":"https:\/\/i1.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2018\/03\/LOGO-hellas-pindakaas.jpg?fit=1734%2C1872&ssl=1","width":1734,"height":1872,"caption":"Hellas Pindakaas"},"image":{"@id":"https:\/\/hellaspindakaas.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HellasPindakaas\/","https:\/\/x.com\/hellaspindakaas","https:\/\/www.instagram.com\/hellaspindakaas\/?hl=en","https:\/\/www.linkedin.com\/in\/nikos-koulousios-5023527\/","https:\/\/www.youtube.com\/user\/nikkokoul\/"]}]}},"_links":{"self":[{"href":"https:\/\/hellaspindakaas.com\/el\/wp-json\/wp\/v2\/tags\/1084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hellaspindakaas.com\/el\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hellaspindakaas.com\/el\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hellaspindakaas.com\/el\/wp-json\/wp\/v2\/posts?tags=1084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}