{"id":2263,"date":"2016-05-30T13:26:57","date_gmt":"2016-05-30T13:26:57","guid":{"rendered":"http:\/\/hellaspindakaas.com\/?p=2263"},"modified":"2016-05-30T13:38:56","modified_gmt":"2016-05-30T13:38:56","slug":"locomondo-live-gogas-photos","status":"publish","type":"post","link":"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/","title":{"rendered":"\u039f\u03b9 Locomondo \u03c3\u03c4\u03bf Melkweg \u03bc\u03b5\u03c3\u03b1 \u03b1\u03c0\u03bf \u03c4\u03bf \u03c6\u03b1\u03ba\u03bf \u03c4\u03bf\u03c5 \u03a3\u03c0\u03c5\u03c1\u03bf\u03c5 \u0393\u03ba\u03bf\u03b3\u03ba\u03b1 &#8211; 26 \u03bc\u03bf\u03bd\u03b1\u03b4\u03b9\u03ba\u03b5\u03c2 \u03c6\u03c9\u03c4\u03bf\u03b3\u03c1\u03b1\u03c6\u03b9\u03b5\u03c2 \u03b1\u03c0\u03bf \u03b5\u03bd\u03b1 \u03be\u03b5\u03c6\u03c1\u03b5\u03bd\u03bf live"},"content":{"rendered":"<p>\u03a4\u03bf\u03bd \u03b5\u03ba\u03c1\u03b7\u03ba\u03c4\u03b9\u03ba\u03cc \u03a3\u03c0\u03cd\u03c1\u03bf \u0393\u03ba\u03cc\u03b3\u03ba\u03b1 \u03c4\u03bf\u03bd \u03be\u03ad\u03c1\u03bf\u03c5\u03bc\u03b5 \u03cc\u03bb\u03bf\u03b9, \u03ba\u03c5\u03c1\u03af\u03c9\u03c2 \u03b2\u03ad\u03b2\u03b1\u03b9\u03b1 \u03b1\u03c5\u03c4\u03bf\u03af \u03c0\u03bf\u03c5 \u03ba\u03b1\u03c4\u03ac\u03b3\u03bf\u03bd\u03c4\u03b1\u03b9 \u03b1\u03c0\u03cc \u03c4\u03b7\u03bd \u03cc\u03bc\u03bf\u03c1\u03c6\u03b7 \u039a\u03ad\u03c1\u03ba\u03c5\u03c1\u03b1 \u03ba\u03b1\u03b9 \u03b1\u03c5\u03c4\u03bf\u03af \u03c0\u03bf\u03c5 \u03b6\u03bf\u03c5\u03bd \u03c3\u03c4\u03bf \u0386\u03bc\u03c3\u03c4\u03b5\u03c1\u03bd\u03c4\u03b1\u03bc. \u0394\u03b5\u03bd \u03c5\u03c0\u03ac\u03c1\u03c7\u03b5\u03b9 \u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae \u03b4\u03c1\u03b1\u03c3\u03c4\u03b7\u03c1\u03b9\u03cc\u03c4\u03b7\u03c4\u03b1 \u03ae \u03ba\u03b1\u03bb\u03bb\u03b9\u03c4\u03b5\u03c7\u03bd\u03b9\u03ba\u03ae \u03ad\u03ba\u03c6\u03c1\u03b1\u03c3\u03b7 \u03c0\u03bf\u03c5 \u03bd\u03b1 \u03bc\u03b7\u03bd \u03c4\u03b7\u03bd \u03ad\u03c7\u03b5\u03b9 \u03b1\u03c0\u03b1\u03b8\u03b1\u03bd\u03b1\u03c4\u03af\u03c3\u03b5\u03b9 \u03bc\u03b5 \u03c4\u03bf \u03c6\u03b1\u03ba\u03cc \u03c4\u03bf\u03c5. \u03a4\u03bf \u03c6\u03b9\u03bb\u03cc\u03c4\u03b9\u03bc\u03bf \u03ba\u03b1\u03b9 \u03b7 \u03b4\u03b9\u03ac\u03b8\u03b5\u03c3\u03b7 \u03b3\u03b9\u03b1 \u03c0\u03c1\u03bf\u03c3\u03c6\u03bf\u03c1\u03ac \u03b5\u03af\u03bd\u03b1\u03b9 \u03c4\u03b1 \u03c0\u03b9\u03bf \u03b4\u03c5\u03bd\u03b1\u03c4\u03ac \u03c4\u03bf\u03c5 \u03c3\u03b7\u03bc\u03b5\u03af\u03b1. \u0397 \u03c4\u03c1\u03ad\u03bb\u03b1 \u03c0\u03bf\u03c5 \u03ba\u03bf\u03c5\u03b2\u03b1\u03bb\u03ac\u03b5\u03b9 \u03c4\u03bf\u03bd \u03ba\u03ac\u03bd\u03b5\u03b9 \u03bd\u03b1 \u03be\u03b5\u03c7\u03c9\u03c1\u03af\u03b6\u03b5\u03b9 \u03b1\u03c0\u03cc \u03c4\u03bf \u03bc\u03ad\u03c3\u03bf \u03cc\u03c1\u03bf. \u039a\u03b1\u03b9 \u03c4\u03ce\u03c1\u03b1 \u03b2\u03ac\u03bb\u03c4\u03b5 \u03b1\u03c5\u03c4\u03cc\u03bd \u03c4\u03bf\u03bd \u03c3\u03af\u03c6\u03bf\u03c5\u03bd\u03b1 \u03c4\u03b7\u03c2 \u03c6\u03c9\u03c4\u03bf\u03b3\u03c1\u03b1\u03c6\u03af\u03b1\u03c2 \u03b4\u03af\u03c0\u03bb\u03b1 \u03c3\u03c4\u03bf\u03c5\u03c2 \u03be\u03b5\u03c3\u03b7\u03ba\u03c9\u03c4\u03b9\u03ba\u03bf\u03cd\u03c2 Locomondo, \u03bf \u03c3\u03c5\u03bd\u03b4\u03bf\u03b9\u03b1\u03c3\u03bc\u03cc\u03c2 \u03b5\u03af\u03bd\u03b1\u03b9 \u03bc\u03bf\u03bd\u03b1\u03b4\u03b9\u03ba\u03cc\u03c2 \u03ba\u03b1\u03b9 \u03b7 \u03ad\u03ba\u03c1\u03b7\u03be\u03b7 \u03c0\u03bf\u03c5 \u03c0\u03b1\u03c1\u03ac\u03b3\u03b5\u03b9 \u03b1\u03c6\u03ae\u03bd\u03b5\u03b9 \u03ba\u03cd\u03bc\u03b1\u03c4\u03b1 \u03b4\u03c1\u03bf\u03c3\u03b9\u03ac\u03c2, \u03b8\u03b5\u03c4\u03b9\u03ba\u03ae\u03c2 \u03b5\u03bd\u03ad\u03c1\u03b3\u03b5\u03b9\u03b1\u03c2 \u03ba\u03b1\u03b9 \u03c6\u03c9\u03c4\u03bf\u03b3\u03c1\u03b1\u03c6\u03b9\u03ba\u03ae\u03c2 \u03bc\u03b1\u03b3\u03b5\u03af\u03b1\u03c2. \u039f \u03a3\u03c0\u03cd\u03c1\u03bf\u03c2 \u03b2\u03c1\u03ad\u03b8\u03b7\u03ba\u03b5 \u03c3\u03c4\u03b7 \u03c3\u03c5\u03bd\u03b1\u03c5\u03bb\u03af\u03b1 \u03c4\u03c9\u03bd Locomondo \u03c4\u03bf \u03c0\u03c1\u03bf\u03b7\u03b3\u03bf\u03cd\u03bc\u03b5\u03bd\u03bf \u03a3\u03ac\u03b2\u03b2\u03b1\u03c4\u03bf \u03c9\u03c2 \u03c3\u03c5\u03bd\u03b5\u03c1\u03b3\u03ac\u03c4\u03b7\u03c2 \u03c4\u03bf\u03c5 Hellas Pindakaas&#8230; \u03ba\u03b1\u03b9 \u03bc\u03ad\u03c3\u03b1 \u03c3\u03b5 \u03bc\u03af\u03b1 \u03ce\u03c1\u03b1 \u03ba\u03b1\u03c4\u03ac\u03c6\u03b5\u03c1\u03b5 \u03bd\u03b1 \u03ba\u03b5\u03c1\u03b4\u03af\u03c3\u03b5\u03b9 \u03c4\u03b7 \u03c3\u03c5\u03bc\u03c0\u03ac\u03b8\u03b5\u03b9\u03b1 \u03ba\u03b1\u03b9 \u03c4\u03b7\u03bd \u03b5\u03ba\u03c4\u03af\u03bc\u03b7\u03c3\u03b7 \u03c4\u03bf\u03c5 \u039c\u03ac\u03c1\u03ba\u03bf\u03c5 \u039a\u03bf\u03cd\u03bc\u03b1\u03c1\u03b7, \u03bf \u03bf\u03c0\u03bf\u03af\u03bf\u03c2 \u03c4\u03bf\u03bd \u03b1\u03bd\u03ad\u03b2\u03b1\u03c3\u03b5 \u03c3\u03c4\u03b7 \u03c3\u03ba\u03b7\u03bd\u03ae \u03b3\u03b9\u03b1 \u03bd\u03b1 \u03c4\u03c1\u03b1\u03b3\u03bf\u03c5\u03b4\u03ae\u03c3\u03bf\u03c5\u03bd \u03bc\u03b1\u03b6\u03af \u03c4\u03bf \u03ba\u03bf\u03bc\u03bc\u03ac\u03c4\u03b9 \u03c4\u03bf\u03c5 Bob Marley Concrete Jungle. \u0392\u03af\u03bd\u03c4\u03b5\u03bf \u03b1\u03c0\u03cc \u03c4\u03b7 \u03c3\u03ba\u03b7\u03bd\u03ae \u03b1\u03c5\u03c4\u03ae \u03ba\u03b1\u03b9 \u03b1\u03c0\u03cc \u03cc\u03bb\u03b7 \u03c4\u03b7 \u03c3\u03c5\u03bd\u03b1\u03c5\u03bb\u03af\u03b1 \u03b8\u03b1 \u03b2\u03c1\u03b5\u03af\u03c4\u03b5 <a href=\"http:\/\/hellaspindakaas.com\/2016\/05\/29\/locomondo-live-amsterdam-videos\/\" target=\"_blank\">\u03c3\u03c4\u03bf \u03c0\u03c1\u03ce\u03c4\u03bf \u03c0\u03bf\u03c3\u03c4 \u03c0\u03bf\u03c5 \u03b1\u03bd\u03b5\u03b2\u03ac\u03c3\u03b1\u03bc\u03b5<\/a> \u03bc\u03b5\u03c4\u03ac \u03c4\u03b7 \u03c3\u03c5\u03bd\u03b1\u03c5\u03bb\u03af\u03b1.<\/p>\n<p>\u0391\u03ba\u03bf\u03cd\u03c3\u03c4\u03b5 <a href=\"http:\/\/hellaspindakaas.com\/2016\/05\/21\/locomondo-interview\/\" target=\"_blank\">\u03b5\u03b4\u03ce \u03c4\u03b7 \u03c3\u03c5\u03bd\u03ad\u03bd\u03c4\u03b5\u03c5\u03be\u03b7<\/a> \u03c0\u03bf\u03c5 \u03ad\u03b4\u03c9\u03c3\u03b5 \u03c0\u03c1\u03b9\u03bd \u03c4\u03b7 \u03c3\u03c5\u03bd\u03b1\u03c5\u03bb\u03af\u03b1 \u03bf \u039c\u03ac\u03c1\u03ba\u03bf\u03c2 \u039a\u03bf\u03cd\u03bc\u03b1\u03c1\u03b7\u03c2 \u03c3\u03c4\u03bf Hellas Pindakaas.<\/p>\n<p>\u03a0\u03c1\u03b9\u03bd \u03ba\u03b1\u03b9 \u03bc\u03b5\u03c4\u03ac \u03c4\u03b7\u03bd \u03c3\u03c5\u03b3\u03ba\u03b9\u03bd\u03b7\u03c4\u03b9\u03ba\u03ae \u03b5\u03bc\u03c6\u03ac\u03bd\u03b9\u03c3\u03b7 \u03c4\u03bf\u03c5 \u03a3\u03c0\u03cd\u03c1\u03bf\u03c5 \u03c3\u03c4\u03b7 \u03c3\u03ba\u03b7\u03bd\u03ae \u03c4\u03c9\u03bd Locomondo, \u03bf \u03c6\u03c9\u03c4\u03bf\u03b3\u03c1\u03ac\u03c6\u03bf\u03c2 \u03ba\u03b1\u03b9 \u03c3\u03c5\u03bd\u03b5\u03c1\u03b3\u03ac\u03c4\u03b7\u03c2 \u03c4\u03b7\u03c2 \u03b5\u03ba\u03c0\u03bf\u03bc\u03c0\u03ae\u03c2 \u03c4\u03c1\u03ac\u03b2\u03b7\u03be\u03b5 26 \u03b1\u03c0\u03cc \u03c4\u03b9\u03c2 \u03c9\u03c1\u03b1\u03b9\u03cc\u03c4\u03b5\u03c1\u03b5\u03c2 \u03c6\u03c9\u03c4\u03bf\u03b3\u03c1\u03b1\u03c6\u03af\u03b5\u03c2 \u03c0\u03bf\u03c5 \u03bc\u03b5\u03c4\u03b1\u03c6\u03ad\u03c1\u03bf\u03c5\u03bd \u03c4\u03bf \u03ba\u03bb\u03af\u03bc\u03b1 \u03c4\u03b7\u03c2 \u03c3\u03c5\u03bd\u03b1\u03c5\u03bb\u03af\u03b1\u03c2 \u03ba\u03b1\u03b9 \u03bc\u03b1\u03c2 \u03b1\u03c6\u03ae\u03bd\u03bf\u03c5\u03bd \u03ad\u03ba\u03c0\u03bb\u03b7\u03ba\u03c4\u03bf\u03c5\u03c2! \u0391\u03c0\u03bf\u03bb\u03b1\u03cd\u03c3\u03c4\u03b5 \u03c4\u03b5\u03c2!<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-2-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2265\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-2-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-2-copy.jpg?fit=1200%2C800\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464469684&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-2-copy.jpg?fit=1024%2C683\" class=\"alignnone size-large wp-image-2265\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-2-copy.jpg?resize=1024%2C683\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-2-copy.jpg?resize=1024%2C683 1024w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-2-copy.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-2-copy.jpg?resize=768%2C512 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-2-copy.jpg?w=1200 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-8-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2258\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/29\/locomondo-live-amsterdam-videos\/locomondo-8-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-8-copy.jpg?fit=1200%2C800\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464470071&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-8-copy.jpg?fit=1024%2C683\" class=\"alignnone size-large wp-image-2258\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-8-copy.jpg?resize=1024%2C683\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-8-copy.jpg?resize=1024%2C683 1024w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-8-copy.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-8-copy.jpg?resize=768%2C512 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-8-copy.jpg?w=1200 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-15-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2266\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-15-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-15-copy.jpg?fit=1200%2C800\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464474554&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-15-copy.jpg?fit=1024%2C683\" class=\"alignnone size-large wp-image-2266\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-15-copy.jpg?resize=1024%2C683\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-15-copy.jpg?resize=1024%2C683 1024w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-15-copy.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-15-copy.jpg?resize=768%2C512 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-15-copy.jpg?w=1200 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-3-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2267\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-3-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-3-copy.jpg?fit=800%2C1200\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464469498&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;108&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-3-copy.jpg?fit=683%2C1024\" class=\" wp-image-2267 aligncenter\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-3-copy.jpg?resize=598%2C897\" alt=\"\" width=\"598\" height=\"897\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-3-copy.jpg?resize=683%2C1024 683w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-3-copy.jpg?resize=200%2C300 200w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-3-copy.jpg?resize=768%2C1152 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-3-copy.jpg?w=800 800w\" sizes=\"auto, (max-width: 598px) 100vw, 598px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-4-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2268\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-4-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-4-copy.jpg?fit=800%2C1200\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464469754&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-4-copy.jpg?fit=683%2C1024\" class=\" wp-image-2268 aligncenter\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-4-copy.jpg?resize=601%2C901\" alt=\"\" width=\"601\" height=\"901\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-4-copy.jpg?resize=683%2C1024 683w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-4-copy.jpg?resize=200%2C300 200w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-4-copy.jpg?resize=768%2C1152 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-4-copy.jpg?w=800 800w\" sizes=\"auto, (max-width: 601px) 100vw, 601px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-28-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2269\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-28-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-28-copy.jpg?fit=800%2C1200\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464473176&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;70&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-28-copy.jpg?fit=683%2C1024\" class=\" wp-image-2269 aligncenter\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-28-copy.jpg?resize=599%2C898\" alt=\"\" width=\"599\" height=\"898\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-28-copy.jpg?resize=683%2C1024 683w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-28-copy.jpg?resize=200%2C300 200w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-28-copy.jpg?resize=768%2C1152 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-28-copy.jpg?w=800 800w\" sizes=\"auto, (max-width: 599px) 100vw, 599px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-10-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2270\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-10-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-10-copy.jpg?fit=800%2C1200\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464471301&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;70&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-10-copy.jpg?fit=683%2C1024\" class=\" wp-image-2270 aligncenter\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-10-copy.jpg?resize=600%2C900\" alt=\"\" width=\"600\" height=\"900\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-10-copy.jpg?resize=683%2C1024 683w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-10-copy.jpg?resize=200%2C300 200w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-10-copy.jpg?resize=768%2C1152 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-10-copy.jpg?w=800 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-36-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2272\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-36-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-36-copy.jpg?fit=1200%2C800\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464470442&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-36-copy.jpg?fit=1024%2C683\" class=\"alignnone size-large wp-image-2272\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-36-copy.jpg?resize=1024%2C683\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-36-copy.jpg?resize=1024%2C683 1024w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-36-copy.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-36-copy.jpg?resize=768%2C512 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-36-copy.jpg?w=1200 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-24-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2273\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-24-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-24-copy.jpg?fit=800%2C1200\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464473250&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;75&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-24-copy.jpg?fit=683%2C1024\" class=\" wp-image-2273 aligncenter\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-24-copy.jpg?resize=598%2C897\" alt=\"\" width=\"598\" height=\"897\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-24-copy.jpg?resize=683%2C1024 683w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-24-copy.jpg?resize=200%2C300 200w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-24-copy.jpg?resize=768%2C1152 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-24-copy.jpg?w=800 800w\" sizes=\"auto, (max-width: 598px) 100vw, 598px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-38-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2274\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-38-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-38-copy.jpg?fit=1200%2C800\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464475490&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.0125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-38-copy.jpg?fit=1024%2C683\" class=\"alignnone size-large wp-image-2274\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-38-copy.jpg?resize=1024%2C683\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-38-copy.jpg?resize=1024%2C683 1024w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-38-copy.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-38-copy.jpg?resize=768%2C512 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-38-copy.jpg?w=1200 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-26-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2275\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-26-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-26-copy.jpg?fit=800%2C1200\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464471225&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;70&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-26-copy.jpg?fit=683%2C1024\" class=\" wp-image-2275 aligncenter\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-26-copy.jpg?resize=598%2C897\" alt=\"\" width=\"598\" height=\"897\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-26-copy.jpg?resize=683%2C1024 683w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-26-copy.jpg?resize=200%2C300 200w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-26-copy.jpg?resize=768%2C1152 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-26-copy.jpg?w=800 800w\" sizes=\"auto, (max-width: 598px) 100vw, 598px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-18-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2276\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-18-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-18-copy.jpg?fit=1200%2C800\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464471170&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;58&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.001&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-18-copy.jpg?fit=1024%2C683\" class=\"alignnone size-large wp-image-2276\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-18-copy.jpg?resize=1024%2C683\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-18-copy.jpg?resize=1024%2C683 1024w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-18-copy.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-18-copy.jpg?resize=768%2C512 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-18-copy.jpg?w=1200 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-13-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2277\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-13-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-13-copy.jpg?fit=800%2C1200\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464473335&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;100&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-13-copy.jpg?fit=683%2C1024\" class=\" wp-image-2277 aligncenter\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-13-copy.jpg?resize=601%2C901\" alt=\"\" width=\"601\" height=\"901\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-13-copy.jpg?resize=683%2C1024 683w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-13-copy.jpg?resize=200%2C300 200w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-13-copy.jpg?resize=768%2C1152 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-13-copy.jpg?w=800 800w\" sizes=\"auto, (max-width: 601px) 100vw, 601px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-33-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2278\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-33-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-33-copy.jpg?fit=1200%2C800\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464470628&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;25&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.0125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-33-copy.jpg?fit=1024%2C683\" class=\"alignnone size-large wp-image-2278\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-33-copy.jpg?resize=1024%2C683\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-33-copy.jpg?resize=1024%2C683 1024w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-33-copy.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-33-copy.jpg?resize=768%2C512 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-33-copy.jpg?w=1200 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-32-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2279\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-32-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-32-copy.jpg?fit=800%2C1200\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464473457&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;70&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-32-copy.jpg?fit=683%2C1024\" class=\" wp-image-2279 aligncenter\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-32-copy.jpg?resize=600%2C900\" alt=\"\" width=\"600\" height=\"900\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-32-copy.jpg?resize=683%2C1024 683w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-32-copy.jpg?resize=200%2C300 200w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-32-copy.jpg?resize=768%2C1152 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-32-copy.jpg?w=800 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-25-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2280\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-25-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-25-copy.jpg?fit=1200%2C800\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464471020&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-25-copy.jpg?fit=1024%2C683\" class=\"alignnone size-large wp-image-2280\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-25-copy.jpg?resize=1024%2C683\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-25-copy.jpg?resize=1024%2C683 1024w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-25-copy.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-25-copy.jpg?resize=768%2C512 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-25-copy.jpg?w=1200 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-5-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2281\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-5-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-5-copy.jpg?fit=800%2C1200\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464469601&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;200&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.003125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-5-copy.jpg?fit=683%2C1024\" class=\" wp-image-2281 aligncenter\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-5-copy.jpg?resize=600%2C900\" alt=\"\" width=\"600\" height=\"900\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-5-copy.jpg?resize=683%2C1024 683w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-5-copy.jpg?resize=200%2C300 200w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-5-copy.jpg?resize=768%2C1152 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-5-copy.jpg?w=800 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-29-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2282\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-29-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-29-copy.jpg?fit=1200%2C800\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464470440&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-29-copy.jpg?fit=1024%2C683\" class=\"alignnone size-large wp-image-2282\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-29-copy.jpg?resize=1024%2C683\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-29-copy.jpg?resize=1024%2C683 1024w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-29-copy.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-29-copy.jpg?resize=768%2C512 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-29-copy.jpg?w=1200 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-37-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2283\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-37-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-37-copy.jpg?fit=800%2C1200\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;7.1&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464475401&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.0166666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-37-copy.jpg?fit=683%2C1024\" class=\" wp-image-2283 aligncenter\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-37-copy.jpg?resize=601%2C901\" alt=\"\" width=\"601\" height=\"901\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-37-copy.jpg?resize=683%2C1024 683w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-37-copy.jpg?resize=200%2C300 200w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-37-copy.jpg?resize=768%2C1152 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-37-copy.jpg?w=800 800w\" sizes=\"auto, (max-width: 601px) 100vw, 601px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-45-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2284\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-45-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-45-copy.jpg?fit=1200%2C800\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464478639&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-45-copy.jpg?fit=1024%2C683\" class=\"alignnone size-large wp-image-2284\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-45-copy.jpg?resize=1024%2C683\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-45-copy.jpg?resize=1024%2C683 1024w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-45-copy.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-45-copy.jpg?resize=768%2C512 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-45-copy.jpg?w=1200 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-39-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2285\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-39-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-39-copy.jpg?fit=1200%2C800\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464477820&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.04&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-39-copy.jpg?fit=1024%2C683\" class=\"alignnone size-large wp-image-2285\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-39-copy.jpg?resize=1024%2C683\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-39-copy.jpg?resize=1024%2C683 1024w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-39-copy.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-39-copy.jpg?resize=768%2C512 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-39-copy.jpg?w=1200 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-43-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2286\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-43-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-43-copy.jpg?fit=800%2C1200\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464478628&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-43-copy.jpg?fit=683%2C1024\" class=\" wp-image-2286 aligncenter\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-43-copy.jpg?resize=600%2C900\" alt=\"\" width=\"600\" height=\"900\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-43-copy.jpg?resize=683%2C1024 683w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-43-copy.jpg?resize=200%2C300 200w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-43-copy.jpg?resize=768%2C1152 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-43-copy.jpg?w=800 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-40-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2287\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-40-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-40-copy.jpg?fit=1200%2C800\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464477720&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.04&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-40-copy.jpg?fit=1024%2C683\" class=\"alignnone size-large wp-image-2287\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-40-copy.jpg?resize=1024%2C683\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-40-copy.jpg?resize=1024%2C683 1024w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-40-copy.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-40-copy.jpg?resize=768%2C512 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-40-copy.jpg?w=1200 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-21-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2288\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-21-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-21-copy.jpg?fit=800%2C1200\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464470276&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-21-copy.jpg?fit=683%2C1024\" class=\" wp-image-2288 aligncenter\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-21-copy.jpg?resize=598%2C897\" alt=\"\" width=\"598\" height=\"897\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-21-copy.jpg?resize=683%2C1024 683w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-21-copy.jpg?resize=200%2C300 200w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-21-copy.jpg?resize=768%2C1152 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-21-copy.jpg?w=800 800w\" sizes=\"auto, (max-width: 598px) 100vw, 598px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-19-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2289\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-19-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-19-copy.jpg?fit=1200%2C800\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464472838&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;25&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-19-copy.jpg?fit=1024%2C683\" class=\"alignnone size-large wp-image-2289\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-19-copy.jpg?resize=1024%2C683\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-19-copy.jpg?resize=1024%2C683 1024w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-19-copy.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-19-copy.jpg?resize=768%2C512 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-19-copy.jpg?w=1200 1200w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-16-copy.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2291\" data-permalink=\"http:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/locomondo-16-copy\/\" data-orig-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-16-copy.jpg?fit=800%2C1200\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark II&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1464473974&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;6400&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-16-copy.jpg?fit=683%2C1024\" class=\" wp-image-2291 aligncenter\" src=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-16-copy.jpg?resize=597%2C895\" alt=\"\" width=\"597\" height=\"895\" srcset=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-16-copy.jpg?resize=683%2C1024 683w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-16-copy.jpg?resize=200%2C300 200w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-16-copy.jpg?resize=768%2C1152 768w, https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-16-copy.jpg?w=800 800w\" sizes=\"auto, (max-width: 597px) 100vw, 597px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>\u03a4\u03bf\u03bd \u03b5\u03ba\u03c1\u03b7\u03ba\u03c4\u03b9\u03ba\u03cc \u03a3\u03c0\u03cd\u03c1\u03bf \u0393\u03ba\u03cc\u03b3\u03ba\u03b1 \u03c4\u03bf\u03bd \u03be\u03ad\u03c1\u03bf\u03c5\u03bc\u03b5 \u03cc\u03bb\u03bf\u03b9, \u03ba\u03c5\u03c1\u03af\u03c9\u03c2 \u03b2\u03ad\u03b2\u03b1\u03b9\u03b1 \u03b1\u03c5\u03c4\u03bf\u03af \u03c0\u03bf\u03c5 \u03ba\u03b1\u03c4\u03ac\u03b3\u03bf\u03bd\u03c4\u03b1\u03b9 \u03b1\u03c0\u03cc \u03c4\u03b7\u03bd \u03cc\u03bc\u03bf\u03c1\u03c6\u03b7 \u039a\u03ad\u03c1\u03ba\u03c5\u03c1\u03b1 \u03ba\u03b1\u03b9 \u03b1\u03c5\u03c4\u03bf\u03af \u03c0\u03bf\u03c5 \u03b6\u03bf\u03c5\u03bd \u03c3\u03c4\u03bf \u0386\u03bc\u03c3\u03c4\u03b5\u03c1\u03bd\u03c4\u03b1\u03bc. \u0394\u03b5\u03bd \u03c5\u03c0\u03ac\u03c1\u03c7\u03b5\u03b9 \u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2258,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18],"tags":[56,95,591,569,736,53,737],"class_list":["post-2263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-going-out","tag-amsterdam","tag-live","tag-locomondo","tag-melkweg","tag-spiros-gogas","tag-53","tag-737"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u039f\u03b9 Locomondo \u03c3\u03c4\u03bf Melkweg \u03bc\u03b5\u03c3\u03b1 \u03b1\u03c0\u03bf \u03c4\u03bf \u03c6\u03b1\u03ba\u03bf \u03c4\u03bf\u03c5 \u03a3\u03c0\u03c5\u03c1\u03bf\u03c5 \u0393\u03ba\u03bf\u03b3\u03ba\u03b1 - 26 \u03bc\u03bf\u03bd\u03b1\u03b4\u03b9\u03ba\u03b5\u03c2 \u03c6\u03c9\u03c4\u03bf\u03b3\u03c1\u03b1\u03c6\u03b9\u03b5\u03c2 \u03b1\u03c0\u03bf \u03b5\u03bd\u03b1 \u03be\u03b5\u03c6\u03c1\u03b5\u03bd\u03bf live - Hellas Pindakaas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/\" \/>\n<meta property=\"og:locale\" content=\"el_GR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u039f\u03b9 Locomondo \u03c3\u03c4\u03bf Melkweg \u03bc\u03b5\u03c3\u03b1 \u03b1\u03c0\u03bf \u03c4\u03bf \u03c6\u03b1\u03ba\u03bf \u03c4\u03bf\u03c5 \u03a3\u03c0\u03c5\u03c1\u03bf\u03c5 \u0393\u03ba\u03bf\u03b3\u03ba\u03b1 - 26 \u03bc\u03bf\u03bd\u03b1\u03b4\u03b9\u03ba\u03b5\u03c2 \u03c6\u03c9\u03c4\u03bf\u03b3\u03c1\u03b1\u03c6\u03b9\u03b5\u03c2 \u03b1\u03c0\u03bf \u03b5\u03bd\u03b1 \u03be\u03b5\u03c6\u03c1\u03b5\u03bd\u03bf live - Hellas Pindakaas\" \/>\n<meta property=\"og:description\" content=\"\u03a4\u03bf\u03bd \u03b5\u03ba\u03c1\u03b7\u03ba\u03c4\u03b9\u03ba\u03cc \u03a3\u03c0\u03cd\u03c1\u03bf \u0393\u03ba\u03cc\u03b3\u03ba\u03b1 \u03c4\u03bf\u03bd \u03be\u03ad\u03c1\u03bf\u03c5\u03bc\u03b5 \u03cc\u03bb\u03bf\u03b9, \u03ba\u03c5\u03c1\u03af\u03c9\u03c2 \u03b2\u03ad\u03b2\u03b1\u03b9\u03b1 \u03b1\u03c5\u03c4\u03bf\u03af \u03c0\u03bf\u03c5 \u03ba\u03b1\u03c4\u03ac\u03b3\u03bf\u03bd\u03c4\u03b1\u03b9 \u03b1\u03c0\u03cc \u03c4\u03b7\u03bd \u03cc\u03bc\u03bf\u03c1\u03c6\u03b7 \u039a\u03ad\u03c1\u03ba\u03c5\u03c1\u03b1 \u03ba\u03b1\u03b9 \u03b1\u03c5\u03c4\u03bf\u03af \u03c0\u03bf\u03c5 \u03b6\u03bf\u03c5\u03bd \u03c3\u03c4\u03bf \u0386\u03bc\u03c3\u03c4\u03b5\u03c1\u03bd\u03c4\u03b1\u03bc. \u0394\u03b5\u03bd \u03c5\u03c0\u03ac\u03c1\u03c7\u03b5\u03b9 \u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/\" \/>\n<meta property=\"og:site_name\" content=\"Hellas Pindakaas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HellasPindakaas\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-30T13:26:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-30T13:38:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-8-copy.jpg?fit=1200%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"HellasPindakaas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hellaspindakaas\" \/>\n<meta name=\"twitter:site\" content=\"@hellaspindakaas\" \/>\n<meta name=\"twitter:label1\" content=\"\u03a3\u03c5\u03bd\u03c4\u03ac\u03c7\u03b8\u03b7\u03ba\u03b5 \u03b1\u03c0\u03cc\" \/>\n\t<meta name=\"twitter:data1\" content=\"HellasPindakaas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/2016\\\/05\\\/30\\\/locomondo-live-gogas-photos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/2016\\\/05\\\/30\\\/locomondo-live-gogas-photos\\\/\"},\"author\":{\"name\":\"HellasPindakaas\",\"@id\":\"http:\\\/\\\/hellaspindakaas.com\\\/#\\\/schema\\\/person\\\/cdc784e7ac5a3d0b56a05156da18433a\"},\"headline\":\"\u039f\u03b9 Locomondo \u03c3\u03c4\u03bf Melkweg \u03bc\u03b5\u03c3\u03b1 \u03b1\u03c0\u03bf \u03c4\u03bf \u03c6\u03b1\u03ba\u03bf \u03c4\u03bf\u03c5 \u03a3\u03c0\u03c5\u03c1\u03bf\u03c5 \u0393\u03ba\u03bf\u03b3\u03ba\u03b1 &#8211; 26 \u03bc\u03bf\u03bd\u03b1\u03b4\u03b9\u03ba\u03b5\u03c2 \u03c6\u03c9\u03c4\u03bf\u03b3\u03c1\u03b1\u03c6\u03b9\u03b5\u03c2 \u03b1\u03c0\u03bf \u03b5\u03bd\u03b1 \u03be\u03b5\u03c6\u03c1\u03b5\u03bd\u03bf live\",\"datePublished\":\"2016-05-30T13:26:57+00:00\",\"dateModified\":\"2016-05-30T13:38:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/2016\\\/05\\\/30\\\/locomondo-live-gogas-photos\\\/\"},\"wordCount\":93,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/hellaspindakaas.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/2016\\\/05\\\/30\\\/locomondo-live-gogas-photos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/hellaspindakaas.com\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Locomondo-8-copy.jpg?fit=1200%2C800\",\"keywords\":[\"amsterdam\",\"live\",\"locomondo\",\"melkweg\",\"spiros gogas\",\"\u03c3\u03c5\u03bd\u03b1\u03c5\u03bb\u03b9\u03b1\",\"\u03c6\u03c9\u03c4\u03bf\u03b3\u03c1\u03b1\u03c6\u03b9\u03b5\u03c2\"],\"articleSection\":[\"\u03a0\u03bf\u03c5 \u03bd\u03b1 \u03b2\u03b3\u03b5\u03b9\u03c4\u03b5\"],\"inLanguage\":\"el\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/2016\\\/05\\\/30\\\/locomondo-live-gogas-photos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/2016\\\/05\\\/30\\\/locomondo-live-gogas-photos\\\/\",\"url\":\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/2016\\\/05\\\/30\\\/locomondo-live-gogas-photos\\\/\",\"name\":\"\u039f\u03b9 Locomondo \u03c3\u03c4\u03bf Melkweg \u03bc\u03b5\u03c3\u03b1 \u03b1\u03c0\u03bf \u03c4\u03bf \u03c6\u03b1\u03ba\u03bf \u03c4\u03bf\u03c5 \u03a3\u03c0\u03c5\u03c1\u03bf\u03c5 \u0393\u03ba\u03bf\u03b3\u03ba\u03b1 - 26 \u03bc\u03bf\u03bd\u03b1\u03b4\u03b9\u03ba\u03b5\u03c2 \u03c6\u03c9\u03c4\u03bf\u03b3\u03c1\u03b1\u03c6\u03b9\u03b5\u03c2 \u03b1\u03c0\u03bf \u03b5\u03bd\u03b1 \u03be\u03b5\u03c6\u03c1\u03b5\u03bd\u03bf live - Hellas Pindakaas\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/hellaspindakaas.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/2016\\\/05\\\/30\\\/locomondo-live-gogas-photos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/2016\\\/05\\\/30\\\/locomondo-live-gogas-photos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/hellaspindakaas.com\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Locomondo-8-copy.jpg?fit=1200%2C800\",\"datePublished\":\"2016-05-30T13:26:57+00:00\",\"dateModified\":\"2016-05-30T13:38:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/2016\\\/05\\\/30\\\/locomondo-live-gogas-photos\\\/#breadcrumb\"},\"inLanguage\":\"el\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/2016\\\/05\\\/30\\\/locomondo-live-gogas-photos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/2016\\\/05\\\/30\\\/locomondo-live-gogas-photos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/hellaspindakaas.com\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Locomondo-8-copy.jpg?fit=1200%2C800\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/hellaspindakaas.com\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Locomondo-8-copy.jpg?fit=1200%2C800\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/2016\\\/05\\\/30\\\/locomondo-live-gogas-photos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/hellaspindakaas.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"amsterdam\",\"item\":\"https:\\\/\\\/hellaspindakaas.com\\\/el\\\/tag\\\/amsterdam\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u039f\u03b9 Locomondo \u03c3\u03c4\u03bf Melkweg \u03bc\u03b5\u03c3\u03b1 \u03b1\u03c0\u03bf \u03c4\u03bf \u03c6\u03b1\u03ba\u03bf \u03c4\u03bf\u03c5 \u03a3\u03c0\u03c5\u03c1\u03bf\u03c5 \u0393\u03ba\u03bf\u03b3\u03ba\u03b1 &#8211; 26 \u03bc\u03bf\u03bd\u03b1\u03b4\u03b9\u03ba\u03b5\u03c2 \u03c6\u03c9\u03c4\u03bf\u03b3\u03c1\u03b1\u03c6\u03b9\u03b5\u03c2 \u03b1\u03c0\u03bf \u03b5\u03bd\u03b1 \u03be\u03b5\u03c6\u03c1\u03b5\u03bd\u03bf live\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/hellaspindakaas.com\\\/#website\",\"url\":\"http:\\\/\\\/hellaspindakaas.com\\\/\",\"name\":\"Hellas Pindakaas\",\"description\":\"online - \u03a4\u03bf \u03bd\u03bf\u03c3\u03c4\u03b9\u03bc\u03bf \u03c1\u03b1\u03b4\u03b9\u03bf\u03c6\u03c9\u03bd\u03bf \u03ba\u03b1\u03b9 \u03c3\u03c4\u03bf \u03b4\u03b9\u03b1\u03b4\u03b9\u03ba\u03c4\u03c5\u03bf\",\"publisher\":{\"@id\":\"http:\\\/\\\/hellaspindakaas.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/hellaspindakaas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"el\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/hellaspindakaas.com\\\/#organization\",\"name\":\"Hellas Pindakaas\",\"url\":\"http:\\\/\\\/hellaspindakaas.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"http:\\\/\\\/hellaspindakaas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/hellaspindakaas.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO-hellas-pindakaas.jpg?fit=1734%2C1872&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/hellaspindakaas.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/LOGO-hellas-pindakaas.jpg?fit=1734%2C1872&ssl=1\",\"width\":1734,\"height\":1872,\"caption\":\"Hellas Pindakaas\"},\"image\":{\"@id\":\"http:\\\/\\\/hellaspindakaas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HellasPindakaas\\\/\",\"https:\\\/\\\/x.com\\\/hellaspindakaas\",\"https:\\\/\\\/www.instagram.com\\\/hellaspindakaas\\\/?hl=en\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/nikos-koulousios-5023527\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/nikkokoul\\\/\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/hellaspindakaas.com\\\/#\\\/schema\\\/person\\\/cdc784e7ac5a3d0b56a05156da18433a\",\"name\":\"HellasPindakaas\",\"url\":\"http:\\\/\\\/hellaspindakaas.com\\\/el\\\/author\\\/hellaspindakaas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u039f\u03b9 Locomondo \u03c3\u03c4\u03bf Melkweg \u03bc\u03b5\u03c3\u03b1 \u03b1\u03c0\u03bf \u03c4\u03bf \u03c6\u03b1\u03ba\u03bf \u03c4\u03bf\u03c5 \u03a3\u03c0\u03c5\u03c1\u03bf\u03c5 \u0393\u03ba\u03bf\u03b3\u03ba\u03b1 - 26 \u03bc\u03bf\u03bd\u03b1\u03b4\u03b9\u03ba\u03b5\u03c2 \u03c6\u03c9\u03c4\u03bf\u03b3\u03c1\u03b1\u03c6\u03b9\u03b5\u03c2 \u03b1\u03c0\u03bf \u03b5\u03bd\u03b1 \u03be\u03b5\u03c6\u03c1\u03b5\u03bd\u03bf live - Hellas Pindakaas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/","og_locale":"el_GR","og_type":"article","og_title":"\u039f\u03b9 Locomondo \u03c3\u03c4\u03bf Melkweg \u03bc\u03b5\u03c3\u03b1 \u03b1\u03c0\u03bf \u03c4\u03bf \u03c6\u03b1\u03ba\u03bf \u03c4\u03bf\u03c5 \u03a3\u03c0\u03c5\u03c1\u03bf\u03c5 \u0393\u03ba\u03bf\u03b3\u03ba\u03b1 - 26 \u03bc\u03bf\u03bd\u03b1\u03b4\u03b9\u03ba\u03b5\u03c2 \u03c6\u03c9\u03c4\u03bf\u03b3\u03c1\u03b1\u03c6\u03b9\u03b5\u03c2 \u03b1\u03c0\u03bf \u03b5\u03bd\u03b1 \u03be\u03b5\u03c6\u03c1\u03b5\u03bd\u03bf live - Hellas Pindakaas","og_description":"\u03a4\u03bf\u03bd \u03b5\u03ba\u03c1\u03b7\u03ba\u03c4\u03b9\u03ba\u03cc \u03a3\u03c0\u03cd\u03c1\u03bf \u0393\u03ba\u03cc\u03b3\u03ba\u03b1 \u03c4\u03bf\u03bd \u03be\u03ad\u03c1\u03bf\u03c5\u03bc\u03b5 \u03cc\u03bb\u03bf\u03b9, \u03ba\u03c5\u03c1\u03af\u03c9\u03c2 \u03b2\u03ad\u03b2\u03b1\u03b9\u03b1 \u03b1\u03c5\u03c4\u03bf\u03af \u03c0\u03bf\u03c5 \u03ba\u03b1\u03c4\u03ac\u03b3\u03bf\u03bd\u03c4\u03b1\u03b9 \u03b1\u03c0\u03cc \u03c4\u03b7\u03bd \u03cc\u03bc\u03bf\u03c1\u03c6\u03b7 \u039a\u03ad\u03c1\u03ba\u03c5\u03c1\u03b1 \u03ba\u03b1\u03b9 \u03b1\u03c5\u03c4\u03bf\u03af \u03c0\u03bf\u03c5 \u03b6\u03bf\u03c5\u03bd \u03c3\u03c4\u03bf \u0386\u03bc\u03c3\u03c4\u03b5\u03c1\u03bd\u03c4\u03b1\u03bc. \u0394\u03b5\u03bd \u03c5\u03c0\u03ac\u03c1\u03c7\u03b5\u03b9 \u03b5\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ae...","og_url":"https:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/","og_site_name":"Hellas Pindakaas","article_publisher":"https:\/\/www.facebook.com\/HellasPindakaas\/","article_published_time":"2016-05-30T13:26:57+00:00","article_modified_time":"2016-05-30T13:38:56+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-8-copy.jpg?fit=1200%2C800&ssl=1","type":"image\/jpeg"}],"author":"HellasPindakaas","twitter_card":"summary_large_image","twitter_creator":"@hellaspindakaas","twitter_site":"@hellaspindakaas","twitter_misc":{"\u03a3\u03c5\u03bd\u03c4\u03ac\u03c7\u03b8\u03b7\u03ba\u03b5 \u03b1\u03c0\u03cc":"HellasPindakaas"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/#article","isPartOf":{"@id":"https:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/"},"author":{"name":"HellasPindakaas","@id":"http:\/\/hellaspindakaas.com\/#\/schema\/person\/cdc784e7ac5a3d0b56a05156da18433a"},"headline":"\u039f\u03b9 Locomondo \u03c3\u03c4\u03bf Melkweg \u03bc\u03b5\u03c3\u03b1 \u03b1\u03c0\u03bf \u03c4\u03bf \u03c6\u03b1\u03ba\u03bf \u03c4\u03bf\u03c5 \u03a3\u03c0\u03c5\u03c1\u03bf\u03c5 \u0393\u03ba\u03bf\u03b3\u03ba\u03b1 &#8211; 26 \u03bc\u03bf\u03bd\u03b1\u03b4\u03b9\u03ba\u03b5\u03c2 \u03c6\u03c9\u03c4\u03bf\u03b3\u03c1\u03b1\u03c6\u03b9\u03b5\u03c2 \u03b1\u03c0\u03bf \u03b5\u03bd\u03b1 \u03be\u03b5\u03c6\u03c1\u03b5\u03bd\u03bf live","datePublished":"2016-05-30T13:26:57+00:00","dateModified":"2016-05-30T13:38:56+00:00","mainEntityOfPage":{"@id":"https:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/"},"wordCount":93,"commentCount":0,"publisher":{"@id":"http:\/\/hellaspindakaas.com\/#organization"},"image":{"@id":"https:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-8-copy.jpg?fit=1200%2C800","keywords":["amsterdam","live","locomondo","melkweg","spiros gogas","\u03c3\u03c5\u03bd\u03b1\u03c5\u03bb\u03b9\u03b1","\u03c6\u03c9\u03c4\u03bf\u03b3\u03c1\u03b1\u03c6\u03b9\u03b5\u03c2"],"articleSection":["\u03a0\u03bf\u03c5 \u03bd\u03b1 \u03b2\u03b3\u03b5\u03b9\u03c4\u03b5"],"inLanguage":"el","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/","url":"https:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/","name":"\u039f\u03b9 Locomondo \u03c3\u03c4\u03bf Melkweg \u03bc\u03b5\u03c3\u03b1 \u03b1\u03c0\u03bf \u03c4\u03bf \u03c6\u03b1\u03ba\u03bf \u03c4\u03bf\u03c5 \u03a3\u03c0\u03c5\u03c1\u03bf\u03c5 \u0393\u03ba\u03bf\u03b3\u03ba\u03b1 - 26 \u03bc\u03bf\u03bd\u03b1\u03b4\u03b9\u03ba\u03b5\u03c2 \u03c6\u03c9\u03c4\u03bf\u03b3\u03c1\u03b1\u03c6\u03b9\u03b5\u03c2 \u03b1\u03c0\u03bf \u03b5\u03bd\u03b1 \u03be\u03b5\u03c6\u03c1\u03b5\u03bd\u03bf live - Hellas Pindakaas","isPartOf":{"@id":"http:\/\/hellaspindakaas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/#primaryimage"},"image":{"@id":"https:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-8-copy.jpg?fit=1200%2C800","datePublished":"2016-05-30T13:26:57+00:00","dateModified":"2016-05-30T13:38:56+00:00","breadcrumb":{"@id":"https:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/#breadcrumb"},"inLanguage":"el","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/"]}]},{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/#primaryimage","url":"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-8-copy.jpg?fit=1200%2C800","contentUrl":"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-8-copy.jpg?fit=1200%2C800","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/hellaspindakaas.com\/el\/2016\/05\/30\/locomondo-live-gogas-photos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/hellaspindakaas.com\/"},{"@type":"ListItem","position":2,"name":"amsterdam","item":"https:\/\/hellaspindakaas.com\/el\/tag\/amsterdam\/"},{"@type":"ListItem","position":3,"name":"\u039f\u03b9 Locomondo \u03c3\u03c4\u03bf Melkweg \u03bc\u03b5\u03c3\u03b1 \u03b1\u03c0\u03bf \u03c4\u03bf \u03c6\u03b1\u03ba\u03bf \u03c4\u03bf\u03c5 \u03a3\u03c0\u03c5\u03c1\u03bf\u03c5 \u0393\u03ba\u03bf\u03b3\u03ba\u03b1 &#8211; 26 \u03bc\u03bf\u03bd\u03b1\u03b4\u03b9\u03ba\u03b5\u03c2 \u03c6\u03c9\u03c4\u03bf\u03b3\u03c1\u03b1\u03c6\u03b9\u03b5\u03c2 \u03b1\u03c0\u03bf \u03b5\u03bd\u03b1 \u03be\u03b5\u03c6\u03c1\u03b5\u03bd\u03bf live"}]},{"@type":"WebSite","@id":"http:\/\/hellaspindakaas.com\/#website","url":"http:\/\/hellaspindakaas.com\/","name":"Hellas Pindakaas","description":"online - \u03a4\u03bf \u03bd\u03bf\u03c3\u03c4\u03b9\u03bc\u03bf \u03c1\u03b1\u03b4\u03b9\u03bf\u03c6\u03c9\u03bd\u03bf \u03ba\u03b1\u03b9 \u03c3\u03c4\u03bf \u03b4\u03b9\u03b1\u03b4\u03b9\u03ba\u03c4\u03c5\u03bf","publisher":{"@id":"http:\/\/hellaspindakaas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/hellaspindakaas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"el"},{"@type":"Organization","@id":"http:\/\/hellaspindakaas.com\/#organization","name":"Hellas Pindakaas","url":"http:\/\/hellaspindakaas.com\/","logo":{"@type":"ImageObject","inLanguage":"el","@id":"http:\/\/hellaspindakaas.com\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2018\/03\/LOGO-hellas-pindakaas.jpg?fit=1734%2C1872&ssl=1","contentUrl":"https:\/\/i1.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2018\/03\/LOGO-hellas-pindakaas.jpg?fit=1734%2C1872&ssl=1","width":1734,"height":1872,"caption":"Hellas Pindakaas"},"image":{"@id":"http:\/\/hellaspindakaas.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HellasPindakaas\/","https:\/\/x.com\/hellaspindakaas","https:\/\/www.instagram.com\/hellaspindakaas\/?hl=en","https:\/\/www.linkedin.com\/in\/nikos-koulousios-5023527\/","https:\/\/www.youtube.com\/user\/nikkokoul\/"]},{"@type":"Person","@id":"http:\/\/hellaspindakaas.com\/#\/schema\/person\/cdc784e7ac5a3d0b56a05156da18433a","name":"HellasPindakaas","url":"http:\/\/hellaspindakaas.com\/el\/author\/hellaspindakaas\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/hellaspindakaas.com\/wp-content\/uploads\/2016\/05\/Locomondo-8-copy.jpg?fit=1200%2C800","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6PQ6c-Av","jetpack-related-posts":[],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"http:\/\/hellaspindakaas.com\/el\/wp-json\/wp\/v2\/posts\/2263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/hellaspindakaas.com\/el\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hellaspindakaas.com\/el\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hellaspindakaas.com\/el\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hellaspindakaas.com\/el\/wp-json\/wp\/v2\/comments?post=2263"}],"version-history":[{"count":1,"href":"http:\/\/hellaspindakaas.com\/el\/wp-json\/wp\/v2\/posts\/2263\/revisions"}],"predecessor-version":[{"id":2295,"href":"http:\/\/hellaspindakaas.com\/el\/wp-json\/wp\/v2\/posts\/2263\/revisions\/2295"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hellaspindakaas.com\/el\/wp-json\/wp\/v2\/media\/2258"}],"wp:attachment":[{"href":"http:\/\/hellaspindakaas.com\/el\/wp-json\/wp\/v2\/media?parent=2263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hellaspindakaas.com\/el\/wp-json\/wp\/v2\/categories?post=2263"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hellaspindakaas.com\/el\/wp-json\/wp\/v2\/tags?post=2263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}